{"id":612,"date":"2016-09-13T15:04:44","date_gmt":"2016-09-13T19:04:44","guid":{"rendered":"http:\/\/simon.wps.dev\/fr\/refinance-calculators\/"},"modified":"2017-10-25T16:06:48","modified_gmt":"2017-10-25T20:06:48","slug":"refinance-calculators","status":"publish","type":"page","link":"https:\/\/bernandofinance.ca\/fr\/refinance\/refinance-calculators\/","title":{"rendered":"Calculateurs de Refinancement"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":508,"parent":627,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bernandofinance.ca\/fr\/refinance\/refinance-calculators\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Calculateurs de Refinancement - Centres Hypoth\u00e9caires Dominion\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bernandofinance.ca\/fr\/refinance\/refinance-calculators\/\" \/>\n<meta property=\"og:site_name\" content=\"Centres Hypoth\u00e9caires Dominion\" \/>\n<meta property=\"article:modified_time\" content=\"2017-10-25T20:06:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bernandofinance.ca\/wp-content\/uploads\/2016\/09\/calculators.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"611\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/bernandofinance.ca\/#organization\",\"name\":\"Centres Hypoth\\u00e9caires Dominion\",\"url\":\"https:\/\/bernandofinance.ca\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/bernandofinance.ca\/#logo\",\"inLanguage\":\"fr-FR\",\"url\":\"http:\/\/master.wps.dlcserver.com\/wp-content\/uploads\/2017\/01\/vector_DLC1.jpg\",\"contentUrl\":\"http:\/\/master.wps.dlcserver.com\/wp-content\/uploads\/2017\/01\/vector_DLC1.jpg\",\"width\":369,\"height\":173,\"caption\":\"Centres Hypoth\\u00e9caires Dominion\"},\"image\":{\"@id\":\"https:\/\/bernandofinance.ca\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/bernandofinance.ca\/#website\",\"url\":\"https:\/\/bernandofinance.ca\/\",\"name\":\"Centres Hypoth\\u00e9caires Dominion\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/bernandofinance.ca\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/bernandofinance.ca\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/bernandofinance.ca\/fr\/refinance\/refinance-calculators\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/bernandofinance.ca\/wp-content\/uploads\/2016\/09\/calculators.jpg\",\"contentUrl\":\"https:\/\/bernandofinance.ca\/wp-content\/uploads\/2016\/09\/calculators.jpg\",\"width\":1200,\"height\":611},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/bernandofinance.ca\/fr\/refinance\/refinance-calculators\/#webpage\",\"url\":\"https:\/\/bernandofinance.ca\/fr\/refinance\/refinance-calculators\/\",\"name\":\"Calculateurs de Refinancement - Centres Hypoth\\u00e9caires Dominion\",\"isPartOf\":{\"@id\":\"https:\/\/bernandofinance.ca\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/bernandofinance.ca\/fr\/refinance\/refinance-calculators\/#primaryimage\"},\"datePublished\":\"2016-09-13T19:04:44+00:00\",\"dateModified\":\"2017-10-25T20:06:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/bernandofinance.ca\/fr\/refinance\/refinance-calculators\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/bernandofinance.ca\/fr\/refinance\/refinance-calculators\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/bernandofinance.ca\/fr\/refinance\/refinance-calculators\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/bernandofinance.ca\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"REFINANCEMENT\",\"item\":\"https:\/\/bernandofinance.ca\/fr\/refinance\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Calculateurs de Refinancement\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bernandofinance.ca\/fr\/refinance\/refinance-calculators\/","og_locale":"fr_FR","og_type":"article","og_title":"Calculateurs de Refinancement - Centres Hypoth\u00e9caires Dominion","og_url":"https:\/\/bernandofinance.ca\/fr\/refinance\/refinance-calculators\/","og_site_name":"Centres Hypoth\u00e9caires Dominion","article_modified_time":"2017-10-25T20:06:48+00:00","og_image":[{"width":1200,"height":611,"url":"https:\/\/bernandofinance.ca\/wp-content\/uploads\/2016\/09\/calculators.jpg","path":"\/var\/www\/sites\/wps\/sites\/code\/wp-content\/uploads\/2016\/09\/calculators.jpg","size":"full","id":508,"alt":"","pixels":733200,"type":"image\/jpeg"}],"twitter_card":"summary","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/bernandofinance.ca\/#organization","name":"Centres Hypoth\u00e9caires Dominion","url":"https:\/\/bernandofinance.ca\/","sameAs":[],"logo":{"@type":"ImageObject","@id":"https:\/\/bernandofinance.ca\/#logo","inLanguage":"fr-FR","url":"http:\/\/master.wps.dlcserver.com\/wp-content\/uploads\/2017\/01\/vector_DLC1.jpg","contentUrl":"http:\/\/master.wps.dlcserver.com\/wp-content\/uploads\/2017\/01\/vector_DLC1.jpg","width":369,"height":173,"caption":"Centres Hypoth\u00e9caires Dominion"},"image":{"@id":"https:\/\/bernandofinance.ca\/#logo"}},{"@type":"WebSite","@id":"https:\/\/bernandofinance.ca\/#website","url":"https:\/\/bernandofinance.ca\/","name":"Centres Hypoth\u00e9caires Dominion","description":"Just another WordPress site","publisher":{"@id":"https:\/\/bernandofinance.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bernandofinance.ca\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","@id":"https:\/\/bernandofinance.ca\/fr\/refinance\/refinance-calculators\/#primaryimage","inLanguage":"fr-FR","url":"https:\/\/bernandofinance.ca\/wp-content\/uploads\/2016\/09\/calculators.jpg","contentUrl":"https:\/\/bernandofinance.ca\/wp-content\/uploads\/2016\/09\/calculators.jpg","width":1200,"height":611},{"@type":"WebPage","@id":"https:\/\/bernandofinance.ca\/fr\/refinance\/refinance-calculators\/#webpage","url":"https:\/\/bernandofinance.ca\/fr\/refinance\/refinance-calculators\/","name":"Calculateurs de Refinancement - Centres Hypoth\u00e9caires Dominion","isPartOf":{"@id":"https:\/\/bernandofinance.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bernandofinance.ca\/fr\/refinance\/refinance-calculators\/#primaryimage"},"datePublished":"2016-09-13T19:04:44+00:00","dateModified":"2017-10-25T20:06:48+00:00","breadcrumb":{"@id":"https:\/\/bernandofinance.ca\/fr\/refinance\/refinance-calculators\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bernandofinance.ca\/fr\/refinance\/refinance-calculators\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/bernandofinance.ca\/fr\/refinance\/refinance-calculators\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bernandofinance.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"REFINANCEMENT","item":"https:\/\/bernandofinance.ca\/fr\/refinance\/"},{"@type":"ListItem","position":3,"name":"Calculateurs de Refinancement"}]}]}},"_links":{"self":[{"href":"https:\/\/bernandofinance.ca\/fr\/wp-json\/wp\/v2\/pages\/612"}],"collection":[{"href":"https:\/\/bernandofinance.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bernandofinance.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bernandofinance.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bernandofinance.ca\/fr\/wp-json\/wp\/v2\/comments?post=612"}],"version-history":[{"count":2,"href":"https:\/\/bernandofinance.ca\/fr\/wp-json\/wp\/v2\/pages\/612\/revisions"}],"predecessor-version":[{"id":1256,"href":"https:\/\/bernandofinance.ca\/fr\/wp-json\/wp\/v2\/pages\/612\/revisions\/1256"}],"up":[{"embeddable":true,"href":"https:\/\/bernandofinance.ca\/fr\/wp-json\/wp\/v2\/pages\/627"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bernandofinance.ca\/fr\/wp-json\/wp\/v2\/media\/508"}],"wp:attachment":[{"href":"https:\/\/bernandofinance.ca\/fr\/wp-json\/wp\/v2\/media?parent=612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}